{"id":8521,"date":"2015-05-27T12:54:59","date_gmt":"2015-05-27T12:54:59","guid":{"rendered":"http:\/\/wp.adg.it\/?page_id=8521"},"modified":"2025-11-18T09:14:51","modified_gmt":"2025-11-18T09:14:51","slug":"workshop-di-arte","status":"publish","type":"page","link":"https:\/\/adg.it\/it\/workshop-di-arte\/","title":{"rendered":"Workshop di arte"},"content":{"rendered":"[spb_text_block title=&#8221;Seminari intensivi settimanali&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;]\n<p>Durante tutto l\u2019arco dell\u2019anno l\u2019Accademia del Giglio organizza seminari e workshop d\u2019arte intensivi della durata di una settimana (alcuni in date specifiche). I corsi si tengono la mattina e il pomeriggio, dal luned\u00ec al venerd\u00ec. Ogni programma consiste in <strong>30 ore di lezione<\/strong>, che si svolgono nel nostro studio d&#8217;arte completamente attrezzato o all&#8217;aperto, nel cuore di Firenze o nei suoi dintorni.<\/p>\n<ul>\n<li>Le lezioni si tengono sia in <strong>italiano<\/strong> che in <strong>inglese<\/strong>.<\/li>\n<li><strong>Tutti i materiali e gli strumenti necessari saranno forniti<\/strong> in loco, quindi non \u00e8 necessario portare nulla con s\u00e9.<\/li>\n<\/ul>\n<p>A AdG <strong>il viaggio inizia con te<\/strong>, non con un programma rigido che limiti la tua creativit\u00e0. Al contrario, <strong>i nostri insegnanti esperti danno priorit\u00e0 alle tue esigenze, capacit\u00e0 e interessi unici<\/strong>, adattando ed evolvendo la tua esperienza di apprendimento ogni giorno. Grazie a una guida attenta e a un sostegno continuo, ti accompagnano passo dopo passo mentre sblocchi e sviluppi la tua voce artistica.<\/p>\n[\/spb_text_block] [spb_text_block title=&#8221;Prezzo speciale&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;]\n<p>Gli studenti che si iscrivono a due o pi\u00f9 <strong>workshop di arte in studio<\/strong>* consecutivi, hanno diritto a uno <strong>sconto** del 10%<\/strong> sul costo dei corsi.<\/p>\n<p>*Offerta valida su una selezione di workshop in studio. Verifica sulla pagina del workshop che desideri frequentare se l&#8217;offerta \u00e8 valida.<\/p>\n<p>**Offerta non cumulabile con altre promozioni.<\/p>\n[\/spb_text_block] [spb_accordion width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_accordion_tab title=&#8221;Disegno e pittura&#8221; accordion_id=&#8221;&#8221; icon=&#8221;&#8221;] [spb_text_block pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;1\/1&#8243; el_position=&#8221;first last&#8221;]\n<p>Frequentando i nostri corsi, gli studenti imparano e progrediscono nelle varie discipline artistiche: possono, per esempio, scoprire i fondamenti del ritratto ed i suoi segreti, affrontare il disegno del nudo con un modello vivente che posa per loro, crearsi un album di schizzi della Firenze storica, applicarsi nello studio dell\u2019effetto luce\/ombra in una natura morta, o anche affrontare tecniche come il trompe-l\u2019oeil e la linoleografia.<\/p>\n[\/spb_text_block] [\/spb_accordion_tab] [spb_accordion_tab title=&#8221;Per principianti ed esperti&#8221; accordion_id=&#8221;&#8221; icon=&#8221;&#8221;] [spb_text_block pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;1\/1&#8243; el_position=&#8221;first last&#8221;]\n<p>Questi workshop sono rivolti agli artisti gi\u00e0 esperti nel disegno o in altre tecniche che vogliono trovare un loro stile o sviluppare la loro creativit\u00e0, ma anche a coloro che vogliono imparare le basi di queste tecniche.<\/p>\n<p>Poich\u00e9 le classi sono formate <strong>mediamente da 6-8 allievi<\/strong> (massimo 10 studenti), ogni studente \u00e8 seguito quasi individualmente dall\u2019insegnante.<\/p>\n<p>Per conoscere le date di ingresso di ciascun seminario, si prega di consultare la pagina di ciascun workshop.<\/p>\n[\/spb_text_block] [\/spb_accordion_tab] [spb_accordion_tab title=&#8221;Date e orari&#8221; accordion_id=&#8221;&#8221; icon=&#8221;&#8221;] [spb_text_block pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;1\/1&#8243; el_position=&#8221;first last&#8221;]\n<p>I workshop possono iniziare <strong>ogni luned\u00ec<\/strong> eccetto quelli con le date indicate nella rispettiva pagina.<\/p>\n<p>I laboratori hanno una durata di 5 giorni, dal luned\u00ec al venerd\u00ec, mattina e pomeriggio, per un totale di 30 ore di lezione (se non specificato nella pagina del corso). <strong>Orario<\/strong> (se non indicato diversamente nella pagina del corso):<\/p>\n<ul>\n<li><strong>Dalle 10.00 alle 13.00 dal luned\u00ec al venerd\u00ec e dalle 13.30 alle 17.00 dal luned\u00ec al gioved\u00ec<\/strong>.<\/li>\n<\/ul>\n<p>In the event of the <a href=\"https:\/\/adg.it\/inglese\/terms.html\">cancellation<\/a> of any of our Art Workshop for reasons beyond our control, we strongly advise participants to acquire a travel insurance that covers the loss of any amounts paid for airfare and accommodation.<\/p>\n[\/spb_text_block] [\/spb_accordion_tab] [spb_accordion_tab title=&#8221;Gruppi&#8221; accordion_id=&#8221;&#8221; icon=&#8221;&#8221;] [spb_text_block pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;1\/1&#8243; el_position=&#8221;first last&#8221;]\n<p>Comunicateci le vostre richieste in merito a date, orari e durata del corso che il vostro gruppo desidera frequentare e vi risponderemo con tutti i dettagli relativi a prezzi speciali, orari e attivit\u00e0 extracurriculari.<\/p>\n[\/spb_text_block] [\/spb_accordion_tab] [spb_accordion_tab title=&#8221;Cambio data facile&#8221; accordion_id=&#8221;&#8221; icon=&#8221;&#8221;] [spb_text_block pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;1\/1&#8243; el_position=&#8221;first last&#8221;]\n<div>Vuoi avere la possibilit\u00e0 di cambiare le date del tuo corso in qualsiasi momento? Acquista per <strong>50 Euro<\/strong> la nostra opzione &#8220;CAMBIO DATA FACILE&#8221; e potrai cambiare o spostare la data del tuo workshop <strong>fino a 24 ore prima<\/strong> dell&#8217;inizio delle lezioni. Questa opzione ti permetter\u00e0 di effettuare fino a un massimo di <strong>due cambi di data<\/strong> di inizio corso senza perdere la tua prenotazione.<\/div>\n<div>La comunicazione di cambio data potr\u00e0 essere effettuata facilmente, inviando una email a <a href=\"mailto:info@adg.it\">info@adg,it<\/a> oppure scrivendo un messaggio Whatsapp a <a href=\"tel:\/\/+393512754681\"><strong>+39 351 2754681<\/strong><\/a> con un un <strong>preavviso di almeno 24 ore<\/strong> dall&#8217;inizio delle lezioni.<\/div>\n<div><\/div>\n[\/spb_text_block] [\/spb_accordion_tab] [\/spb_accordion] [blank_spacer height=&#8221;30px&#8221; width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;21225&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/sketchbook-di-firenze-e-paesaggismo&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Sketchbook di Firenze e paesaggismo&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Se desiderate scoprire la poesia e la magia di Firenze e l&#8217;atmosfera rilassante della campagna toscana, questo \u00e8 il vostro workshop!<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/sketchbook-di-firenze-e-paesaggismo\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6304&#8243; image_size=&#8221;full&#8221; frame=&#8221;borderframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-ritratto-autoritratto\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Ritratto e autoritratto&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Il corso per migliorare lo stile e la creativit\u00e0, ma anche per scoprire i segreti e i trucchi per disegnare o dipingere un ritratto o un autoritratto.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-ritratto-autoritratto\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;16081&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-nudo-artistico\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Nudo artistico&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Modelli viventi saranno a disposizione per lo studio dell\u2019anatomia, del corpo e del volto seguendo i metodi tradizionali e moderni.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-nudo-artistico\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;15935&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-pittura-olio\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Workshop di pittura a olio&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Impara le tecniche della pittura a olio usate dai pittori del Rinascimento e dell&#8217;Impressionismo.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-pittura-olio\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;17357&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/tecniche-di-pittura-a-tempera-del-rinascimento\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Pittura a tempera del Rinascimento&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Impara la tecnica della tempera all&#8217;uovo e padroneggia le altre tecniche rinascimentali.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/tecniche-di-pittura-a-tempera-del-rinascimento\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;16648&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-pittura-ad-acrilico\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Pittura ad acrilico&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Per imparare ad applicare i colori in strati sottili, o campiture, per produrre effetti acquerello o realizzare strati spessi dello stesso colore per creare rilievi.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-pittura-ad-acrilico\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6260&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-disegno-a-sanguigna-e-carboncino\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Disegno classico&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un\u2019immersione nelle classiche tecniche del disegno per studiare gli effetti della luce e delle ombre sugli oggetti o sulle persone. Per principianti e avanzati.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-disegno-a-sanguigna-e-carboncino\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;24908&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/pittura-grandi-maestri\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;La pittura dei Grandi Maestri&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Il workshop per imparare a dipingere come i Grandi Maestri.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/pittura-grandi-maestri\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;27400&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-acquerello\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Acquerello&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un workshop in studio o tra i colori delicati dei palazzi di Firenze, tra le luci del fiume Arno e i suoi ponti, in mezzo alla natura della campagna toscana.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-acquerello\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;21309&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-pastello-a-olio-e-gessetto\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Pastello e gessetti&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Per imparare attraverso esercizi pratici i molteplici utilizzi del pastello e del gessetto e tutte le potenzialit\u00e0 di queste tecniche.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-pastello-a-olio-e-gessetto\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;23295&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/arte-viva\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Arte viva\/Natura morta&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Libera il tuo potenziale artistico con il corso di disegno e pittura dal vero. Impara a catturare la bellezza degli oggetti attraverso rappresentazioni accurate.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/arte-viva\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6315&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-affresco\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Affresco&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Uno studio dei segreti di questa antica tecnica che vi permetter\u00e0 di acquisire le nozioni principali per la realizzazione di un affresco.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-affresco\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6341&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-trompeloeil\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Trompe l&#8217;oeil&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Il corso per imparare a creare oggetti tridimensionali attraverso antiche tecniche di disegno, colore e sapiente uso della prospettiva.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-trompeloeil\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6196&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-scultura\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Scultura&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Scopri i fondamenti della scultura: bassorilievo, tutto tondo e colombino.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-scultura\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;17774&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-pittura-astratta\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Workshop di pittura astratta&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Supera il realismo e dipingi le tue idee e le tue emozioni praticando diversi tipi di arte non rappresentativa come l\u2019astrazione geometrica, l\u2019astrazione lirica e l\u2019astrazione parziale.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-pittura-astratta\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;17116&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-pittura-fluida\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Pittura fluida&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Impara a combinare colori liquidi per creare opere sorprendenti.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-pittura-fluida\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;20887&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/mixed-media-workshop\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Mixed media&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Scopri il potenziale di mescolare pi\u00f9 materiali differenti in un\u2019unica opera d\u2019arte.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/mixed-media-workshop\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;19783&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/moda-illustrazione\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Illustrazione di moda&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Per imparare a tradurre in un\u2019illustrazione di moda un\u2019immagine o una forma e per disegnare abiti e tessuti.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/moda-illustrazione\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6219&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-decorazione\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Decorazione&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Impara a creare gli effetti del marmo, del legno e delle pietre dure.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-decorazione\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6357&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-decorazione\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Arte nei musei di Firenze&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un\u2019occasione unica per poter ammirare le opere d\u2019arte dei musei fiorentini e allo stesso tempo disegnarle sul proprio quaderno di schizzi o dipingerle su tela.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-decorazione\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6308&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-pittura-da-fotografia\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Pittura da fotografia&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Il corso per imparare a trasformare le vostre fotografie pi\u00f9 belle (ritratti, animali, paesaggi e nature morte) in disegni o dipinti.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-pittura-da-fotografia\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6297&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/dipingere-fiori\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Dipingere i fiori&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Il corso perfetto per chi ama la natura nella sua espressione pi\u00f9 romantica. Un seminario intensivo per imparare a dipingere artisticamente i fiori.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/dipingere-fiori\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6363&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/dipingere-animali\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Dipingere gli animali&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Il corso che vi dar\u00e0 tutte le informazioni, i consigli e i segreti per imparare a dipingere il vostro animale preferito.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/dipingere-animali\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6432&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-illustrazione\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Workshop di scenografia&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un lavoro sulla progettazione scenica e del costume sviluppando le abilit\u00e0 di disegno a mano libera.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-illustrazione\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6422&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-linoleografia\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Linoleografia&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un seminario intensivo per imparare la tecnica di base dell\u2019incisione attraverso prove su linoleum o legno e lo studio dei diversi tipi di effetti.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-linoleografia\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6417&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-paesaggio-natura-marina&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Paesaggio, natura e marina&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Disegno e pittura \u201cen plein air\u201d a Firenze, nella campagna toscana, in una riserva naturale e al mare.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-paesaggio-natura-marina\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;17382&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/dipingere-in-toscana\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Dipingere in Toscana&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Disegnare e dipingere a Firenze, Pisa, Lucca, Siena e Arezzo<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/dipingere-in-toscana\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;13577&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/paesaggio-urbano-architettura\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Paesaggio urbano e architettura&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Disegno a mano libera di paesaggi urbani e degli elementi architettonici del paesaggio.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/paesaggio-urbano-architettura\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;20332&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/scenografia-workshop\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Workshop di scenografia&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Scopri come immaginare e disegnare vari tipi di scenari e costumi per film e spettacoli teatrali.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/scenografia-workshop\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;11947&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/costume\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Workshop di disegno del costume&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un workshop per imparare a disegnare e dipingere vestiti e drappeggi.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/costume\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;8580&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/en\/art-classes-in-front-of-the-sea\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Pittura di marina&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Aggiungi al tuo corso d\u2019arte una giornata di pittura e relax al mare di Castiglioncello.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/en\/art-classes-in-front-of-the-sea\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;21051&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/5-tecniche-in-5-giorni\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;5 techniche in 5 giorni&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Studia 5 tecniche artistiche in 5 giorni: scegli tra un\u2019ampia variet\u00e0 di tecniche e materie come la pittura a olio, il disegno, l\u2019affresco, il ritratto e tante altre ancora.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/5-tecniche-in-5-giorni\/\" target=\"_self\"><span class=\"text\">Informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column] [spb_column width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] [spb_single_image image=&#8221;6408&#8243; image_size=&#8221;full&#8221; frame=&#8221;glowframe&#8221; intro_animation=&#8221;none&#8221; full_width=&#8221;no&#8221; lightbox=&#8221;no&#8221; image_link=&#8221;https:\/\/adg.it\/it\/workshop-di-arte-combinato\/&#8221; link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; el_position=&#8221;first&#8221;] [spb_text_block title=&#8221;Workshop d&#8217;arte combinato&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;2\/3&#8243; el_position=&#8221;last&#8221;]\n<p style=\"text-align: center;\">Un corso per studiare una o pi\u00f9 tecniche artistiche a scelta dello studente, combinando 10 ore di lezione privata con 14 ore di lezione di gruppo.<\/p>\n<p style=\"text-align: center;\"><a class=\"sf-button standard orange standard  dropshadow\" href=\"https:\/\/adg.it\/it\/workshop-di-arte-combinato\/\" target=\"_self\"><span class=\"text\">Altre informazioni<\/span><\/a><\/p>\n[\/spb_text_block] [\/spb_column]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[spb_text_block title=&#8221;Seminari intensivi settimanali&#8221; pb_margin_bottom=&#8221;no&#8221; pb_border_bottom=&#8221;no&#8221; width=&#8221;3\/4&#8243; el_position=&#8221;first last&#8221;] Durante tutto l\u2019arco dell\u2019anno l\u2019Accademia del Giglio organizza seminari e workshop d\u2019arte intensivi della durata di una settimana (alcuni in date specifiche). I corsi si tengono la mattina e il pomeriggio, dal luned\u00ec al venerd\u00ec. Ogni programma consiste in 30 ore di lezione, che si svolgono nel nostro studio d&#8217;arte completamente [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-8521","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d&#039;arte AdG di Firenze.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"yEEw7qpW9exgWfaHTE64VYQ-7zNKuI26nN_iKukATSY\" \/>\n\t<meta name=\"keywords\" content=\"sketchbook a firenze,pittura di paesaggio firenze,workshop estivi di pittura a firenze,corso di ritratto a firenze,workshop estivo di acquerello,workshop di disegno a sanguigna\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/adg.it\/it\/workshop-di-arte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Accademia del Giglio | Scuola di arte e italiano a Firenze\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Workshop e laboratori di arte a Firenze | Accademia del Giglio\" \/>\n\t\t<meta property=\"og:description\" content=\"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d&#039;arte AdG di Firenze.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/adg.it\/it\/workshop-di-arte\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/adg.it\/wp-content\/uploads\/2022\/12\/scritta-adg-2022-ita.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/adg.it\/wp-content\/uploads\/2022\/12\/scritta-adg-2022-ita.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-05-27T12:54:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-18T09:14:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccademiaGiglio\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AccademiaGiglio\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Workshop e laboratori di arte a Firenze | Accademia del Giglio\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d&#039;arte AdG di Firenze.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AccademiaGiglio\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/adg.it\/wp-content\/uploads\/2022\/12\/scritta-adg-2022-ita.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adg.it\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#listItem\",\"name\":\"Workshop di arte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#listItem\",\"position\":2,\"name\":\"Workshop di arte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/#organization\",\"name\":\"Accademia del Giglio\",\"description\":\"Scuola di arte e italiano a Firenze\",\"url\":\"https:\\\/\\\/adg.it\\\/it\\\/\",\"telephone\":\"+393512754681\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/adg.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/cropped-logo-adg-tab-1.jpg\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccademiaGiglio\",\"https:\\\/\\\/twitter.com\\\/AccademiaGiglio\",\"https:\\\/\\\/www.instagram.com\\\/accademiadelgiglio\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/adgblog\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/accademiadelgiglio\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/accademia-del-giglio\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#webpage\",\"url\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/\",\"name\":\"Workshop e laboratori di arte a Firenze | Accademia del Giglio\",\"description\":\"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d'arte AdG di Firenze.\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/workshop-di-arte\\\/#breadcrumblist\"},\"datePublished\":\"2015-05-27T12:54:59+00:00\",\"dateModified\":\"2025-11-18T09:14:51+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/adg.it\\\/it\\\/\",\"name\":\"Accademia del Giglio\",\"description\":\"Scuola di arte e italiano a Firenze\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/adg.it\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Workshop e laboratori di arte a Firenze | Accademia del Giglio","description":"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d'arte AdG di Firenze.","canonical_url":"https:\/\/adg.it\/it\/workshop-di-arte\/","robots":"max-image-preview:large","keywords":"sketchbook a firenze,pittura di paesaggio firenze,workshop estivi di pittura a firenze,corso di ritratto a firenze,workshop estivo di acquerello,workshop di disegno a sanguigna","webmasterTools":{"google-site-verification":"yEEw7qpW9exgWfaHTE64VYQ-7zNKuI26nN_iKukATSY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/adg.it\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/adg.it\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#listItem","name":"Workshop di arte"}},{"@type":"ListItem","@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#listItem","position":2,"name":"Workshop di arte","previousItem":{"@type":"ListItem","@id":"https:\/\/adg.it\/it\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/adg.it\/it\/#organization","name":"Accademia del Giglio","description":"Scuola di arte e italiano a Firenze","url":"https:\/\/adg.it\/it\/","telephone":"+393512754681","logo":{"@type":"ImageObject","url":"https:\/\/adg.it\/wp-content\/uploads\/2019\/04\/cropped-logo-adg-tab-1.jpg","@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/AccademiaGiglio","https:\/\/twitter.com\/AccademiaGiglio","https:\/\/www.instagram.com\/accademiadelgiglio\/","https:\/\/www.pinterest.it\/adgblog\/","https:\/\/www.youtube.com\/c\/accademiadelgiglio","https:\/\/www.linkedin.com\/school\/accademia-del-giglio\/"]},{"@type":"WebPage","@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#webpage","url":"https:\/\/adg.it\/it\/workshop-di-arte\/","name":"Workshop e laboratori di arte a Firenze | Accademia del Giglio","description":"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d'arte AdG di Firenze.","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/adg.it\/it\/#website"},"breadcrumb":{"@id":"https:\/\/adg.it\/it\/workshop-di-arte\/#breadcrumblist"},"datePublished":"2015-05-27T12:54:59+00:00","dateModified":"2025-11-18T09:14:51+00:00"},{"@type":"WebSite","@id":"https:\/\/adg.it\/it\/#website","url":"https:\/\/adg.it\/it\/","name":"Accademia del Giglio","description":"Scuola di arte e italiano a Firenze","inLanguage":"it-IT","publisher":{"@id":"https:\/\/adg.it\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Accademia del Giglio | Scuola di arte e italiano a Firenze","og:type":"article","og:title":"Workshop e laboratori di arte a Firenze | Accademia del Giglio","og:description":"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d'arte AdG di Firenze.","og:url":"https:\/\/adg.it\/it\/workshop-di-arte\/","og:image":"https:\/\/adg.it\/wp-content\/uploads\/2022\/12\/scritta-adg-2022-ita.png","og:image:secure_url":"https:\/\/adg.it\/wp-content\/uploads\/2022\/12\/scritta-adg-2022-ita.png","article:published_time":"2015-05-27T12:54:59+00:00","article:modified_time":"2025-11-18T09:14:51+00:00","article:publisher":"https:\/\/www.facebook.com\/AccademiaGiglio","twitter:card":"summary","twitter:site":"@AccademiaGiglio","twitter:title":"Workshop e laboratori di arte a Firenze | Accademia del Giglio","twitter:description":"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d'arte AdG di Firenze.","twitter:creator":"@AccademiaGiglio","twitter:image":"https:\/\/adg.it\/wp-content\/uploads\/2022\/12\/scritta-adg-2022-ita.png"},"aioseo_meta_data":{"post_id":"8521","title":"Workshop e laboratori di arte a Firenze | #site_title","description":"Workshop settimanali estivi e invernali a Firenze: corsi intensivi delle tecniche classiche di disegno e pittura presso la scuola d'arte AdG di Firenze.","keywords":[{"label":"sketchbook a firenze","value":"sketchbook a firenze"},{"label":"pittura di paesaggio firenze","value":"pittura di paesaggio firenze"},{"label":"workshop estivi di pittura a firenze","value":"workshop estivi di pittura a firenze"},{"label":"corso di ritratto a firenze","value":"corso di ritratto a firenze"},{"label":"workshop estivo di acquerello","value":"workshop estivo di acquerello"},{"label":"workshop di disegno a sanguigna","value":"workshop di disegno a sanguigna"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2021-02-16 09:53:16","updated":"2025-11-18 09:14:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/adg.it\/it\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWorkshop di arte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/adg.it\/it\/"},{"label":"Workshop di arte","link":"https:\/\/adg.it\/it\/workshop-di-arte\/"}],"_links":{"self":[{"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/pages\/8521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/comments?post=8521"}],"version-history":[{"count":4,"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/pages\/8521\/revisions"}],"predecessor-version":[{"id":27401,"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/pages\/8521\/revisions\/27401"}],"wp:attachment":[{"href":"https:\/\/adg.it\/it\/wp-json\/wp\/v2\/media?parent=8521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}